{"id":4255833,"date":"2021-12-08T16:41:23","date_gmt":"2021-12-08T16:41:23","guid":{"rendered":"https:\/\/www.deptagency.com\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/"},"modified":"2021-12-08T16:41:23","modified_gmt":"2021-12-08T16:41:23","slug":"eine-virtuelle-zeitreise-durch-die-musikgeschichte","status":"publish","type":"case","link":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/","title":{"rendered":"Eine virtuelle Zeitreise durch die Musikgeschichte"},"content":{"rendered":"<div class=\"block-case-post-header block-case-post-header__theme--white\">\n\t<a\tclass=\"cta-button block-case-post-header__back-button cta-button__color--onyxGrey cta-button__style--back\" href=\"https:\/\/www.deptagency.com\/work\/\" aria-label=\"Back\" >\n\t<svg width='41' height='41' viewBox='0 0 41 41' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'><circle cx='20.5' cy='20.5' r='19.5' transform='rotate(-90 20.5 20.5)' stroke='var(--dept-button-icon-outline-color)' stroke-width='1.3' stroke-miterlimit='10' fill='none'\/><circle class='icon-backplate' cx='20.5' cy='20.5' r='19.5' transform='rotate(-90 20.5 20.5)' fill='var(--dept-button-icon-backplate-color)' fill-opacity='1'\/><path class='icon-center' d='M21.174 30 11 20.674l10.174-9.326m-9.326 9.328H30.5' stroke='var(--dept-button-icon-color)' stroke-width='1.3' stroke-miterlimit='10' fill='none'\/><\/svg>\n\t\n<\/a><h2\t\tclass=\"typography block-case-post-header__tag typography__color--onyxGrey typography__size--regular-body typography__align--left\"\n\t\t\t>\n\t\tHitparade.ch\t<\/h2><h1\t\tclass=\"typography block-case-post-header__heading typography__color--onyxGrey typography__size--h2 typography__align--left\"\n\t\t\t>\n\t\tEine virtuelle Zeitreise durch die Musikgeschichte\t<\/h1><\/div>\n\n<div\n\t\tclass=\"image-wrap block-image__image-wrap\"\n\t\tdata-align=\"center center\"\n\t\t\t>\n\n\t\t\t<picture\n\t\tclass=\"image__picture\"\n\t\t\t\t>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<img\n\t\t\t\tsrc=\"https:\/\/www.deptagency.com\/wp-content\/uploads\/2021\/12\/50-years-swiss-music-charts.jpg\"\n\t\t\t\tclass=\"image block-image__image\"\n\n\t\t\t\t\t\t\t\talt=\"50 years swiss music charts \"\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\/>\n\t\t<\/picture>\n\t\n\t<\/div>\n\n<div class=\"block-statement block-statement__background-color--white block-statement__align--left\">\n\t<p\t\tclass=\"typography block-statement__title typography__color--onyxGrey typography__size--h5 typography__align--left\"\n\t\t\t>\n\t\t<br><br>Was w\u00e4re, wenn man in die Vergangenheit reisen k\u00f6nnte, um zu h\u00f6ren, wie die Schweizer Hitparade in den letzten 50 Jahren geklungen hat? Zusammen mit den Datenexpert:innen von D One haben wir f\u00fcr das grosse Jubil\u00e4um der Schweizer Hitparade eine ganz spezielle Website kreiert: Die User:innen tauchen in einen digitalen Zeit-Klang-Kosmos ein und scrollen durch ein halbes Jahrhundert Musikgeschichte &#8211; von Hit zu Hit, die wie Sterne am Himmel auftauchen. Die Reise beginnt am 2. Januar 1968 mit dem damaligen Nr. 1-Hit &#8220;Monja&#8221; und f\u00fchrt zu Ed Sheerans &#8220;Perfect&#8221;, der Anfang dieses Jahres auf Platz 1 stand. Dazwischen finden User:innen alle 10&#8217;939 Songs, die es seit Beginn in die offiziellen CH-Charts geschafft haben. Wir laden User:innen ein, nostalgisch zu werden und sich wieder neu in die Musik zu verlieben.\t<\/p><\/div>\n\n<div class=\"block-title-and-content js-block-title-and-content block-title-and-content__theme--onyxGrey\">\n\t<div class=\"block-title-and-content__layout\">\n\t\t<h2\t\tclass=\"typography block-title-and-content__title typography__color--white typography__size--h2 typography__align--left\"\n\t\tdata-size-mobile=\"h2\" \t>\n\t\tData Driven Web Experience\t<\/h2>\n\t\t\t\t\t<div class=\"block-title-and-content__content\">\n\t\t\t\t\n<div class='block-title-and-content__item'><div class='block-title-and-content__item-inner'><p\t\tclass=\"typography block-typography__typography typography__color--lightGrey typography__size--regular-body typography__align--left\"\n\t\t\t>\n\t\tDer gerade gespielte Song kann mit den wichtigsten Informationen &#8211; Musiker:in, Titel, Datum und Rang sowie alle Positionen im Ranking &#8211; eingesehen werden. Eine automatisierte Abfrage von Parametern bei Spotify hilft, jeden Song zu charakterisieren, und macht die Stimmung der Musik sichtbar. Je weiter links ein Song platziert ist, desto langsamer und melancholischer ist dieser, je weiter rechts, desto schneller und fr\u00f6hlicher ist er.\t<\/p><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\t<div class=\"block-title-and-content__social-links\">\n\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"copy\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Copy page link\"\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tdata-tooltip=\"true\"\n\t\t\t\t\tdata-tooltip-text=\"Link copied to clipboard.\"\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg' width='22' height='22' viewBox='0 0 22 22'><path d='M6.832 15.167l8.333-8.333M9.332 6.001l2.787-2.787a4.715 4.715 0 016.666 0v0a4.715 4.715 0 010 6.667L16 12.668M5.999 9.334l-2.787 2.787a4.715 4.715 0 000 6.666v0a4.715 4.715 0 006.667 0l2.787-2.786' stroke='currentColor' stroke-width='2'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"facebook\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Facebook\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg width='14' height='22' viewBox='0 0 14 22' fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg'><path d='M4.032 22L4 12H0V8h4V5.5C4 1.789 6.298 0 9.61 0c1.585 0 2.948.118 3.345.17v3.88H10.66c-1.8 0-2.15.856-2.15 2.112V8h5.241l-2 4H8.51v10H4.032z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"whatsapp\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Whatsapp\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg xmlns='http: \/\/www.w3.org\/2000\/svg' width='25' height='24' viewBox='0 0 25 24'><path d='M.805 24l1.687-6.163a11.869 11.869 0 01-1.588-5.945C.907 5.335 6.244 0 12.801 0c3.182.001 6.17 1.24 8.415 3.488a11.819 11.819 0 013.481 8.413c-.002 6.558-5.34 11.893-11.896 11.893h-.005c-1.99-.001-3.947-.5-5.685-1.448L.805 24zm6.598-3.807l.361.214a9.874 9.874 0 005.033 1.378h.004c5.45 0 9.885-4.434 9.888-9.885a9.824 9.824 0 00-2.894-6.993 9.823 9.823 0 00-6.99-2.898c-5.454 0-9.89 4.434-9.892 9.884a9.86 9.86 0 001.512 5.26l.235.374-.999 3.648 3.742-.982z' fill='currentColor'\/><path d='M9.825 6.921c-.24-.58-.486-.501-.668-.51-.174-.009-.372-.01-.57-.01-.198 0-.52.074-.793.371-.272.298-1.04 1.017-1.04 2.48 0 1.462 1.065 2.875 1.214 3.073.148.199 2.096 3.2 5.078 4.487.709.306 1.262.49 1.694.626.712.226 1.36.194 1.872.118.571-.085 1.759-.72 2.007-1.413.247-.694.247-1.29.173-1.413-.074-.124-.272-.199-.57-.347-.297-.149-1.758-.868-2.03-.967-.273-.1-.471-.149-.67.149-.198.297-.767.966-.94 1.165-.174.198-.348.223-.645.074-.297-.149-1.255-.462-2.39-1.475-.884-.788-1.48-1.76-1.654-2.058-.173-.298-.018-.459.13-.607.134-.133.298-.347.446-.52.149-.174.199-.298.298-.496.099-.198.05-.372-.025-.52-.074-.15-.669-1.612-.917-2.207z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F&#038;text=Eine%20virtuelle%20Zeitreise%20durch%20die%20Musikgeschichte\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"twitter\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Twitter\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg width='25' height='20' viewBox='0 0 25 20' fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg'><path d='M24.75 2.3c-.9.4-1.8.7-2.8.8 1-.6 1.8-1.6 2.2-2.7-1 .6-2 1-3.1 1.2-.9-1-2.2-1.6-3.6-1.6-2.7 0-4.9 2.2-4.9 4.9 0 .4 0 .8.1 1.1-4.2-.2-7.8-2.2-10.2-5.2-.5.8-.7 1.6-.7 2.5 0 1.7.9 3.2 2.2 4.1-.8 0-1.6-.2-2.2-.6v.1c0 2.4 1.7 4.4 3.9 4.8-.4.1-.8.2-1.3.2-.3 0-.6 0-.9-.1.6 2 2.4 3.4 4.6 3.4-1.7 1.3-3.8 2.1-6.1 2.1-.4 0-.8 0-1.2-.1 2.2 1.4 4.8 2.2 7.5 2.2 9.1 0 14-7.5 14-14v-.6c1-.7 1.8-1.6 2.5-2.5z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"linkedin\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Linkedin\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg width='19' height='18' viewBox='0 0 19 18' fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg'><path d='M1.15 17.3h3.6V5.8h-3.6v11.5zM.75 2.1c0 1.2 1 2.1 2.1 2.1 1.2 0 2.1-.9 2.1-2.1 0-1.2-1-2.1-2.1-2.1-1.2 0-2.1 1-2.1 2.1zM14.45 17.3h3.6v-6.2c0-3.1-.7-5.5-4.3-5.5-1.8 0-2.9.9-3.4 1.8V5.8h-3.4v11.5h3.6v-5.7c0-1.5.2-2.9 2.1-2.9 1.8 0 1.8 1.7 1.8 3v5.6z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t<\/div>\n<\/div>\n\n<div class=\"block-title-and-content js-block-title-and-content block-title-and-content__theme--white\">\n\t<div class=\"block-title-and-content__layout\">\n\t\t<h2\t\tclass=\"typography block-title-and-content__title typography__color--onyxGrey typography__size--h2 typography__align--left\"\n\t\tdata-size-mobile=\"h2\" \t>\n\t\t<br>Performance first\t<\/h2>\n\t\t\t\t\t<div class=\"block-title-and-content__content\">\n\t\t\t\t\n<div class='block-title-and-content__item'><div class='block-title-and-content__item-inner'><p\t\tclass=\"typography block-typography__typography typography__color--onyxGrey typography__size--regular-body typography__align--left\"\n\t\t\t>\n\t\tDie Website bietet ein spektakul\u00e4res und emotionales Erlebnis, w\u00e4hrend die Technologie dahinter komplex und intelligent ist. Wie bew\u00e4ltigt die Plattform die riesigen Datenmengen, ohne Kompromisse bei Geschwindigkeit und Darstellungsqualit\u00e4t einzugehen? &#8220;Ein bisschen wie Magie&#8221;, wie unser Frontend-Guru Severin Klaus sagen w\u00fcrde.\t<\/p><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\t<div class=\"block-title-and-content__social-links\">\n\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"copy\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Copy page link\"\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tdata-tooltip=\"true\"\n\t\t\t\t\tdata-tooltip-text=\"Link copied to clipboard.\"\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg' width='22' height='22' viewBox='0 0 22 22'><path d='M6.832 15.167l8.333-8.333M9.332 6.001l2.787-2.787a4.715 4.715 0 016.666 0v0a4.715 4.715 0 010 6.667L16 12.668M5.999 9.334l-2.787 2.787a4.715 4.715 0 000 6.666v0a4.715 4.715 0 006.667 0l2.787-2.786' stroke='currentColor' stroke-width='2'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"facebook\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Facebook\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg width='14' height='22' viewBox='0 0 14 22' fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg'><path d='M4.032 22L4 12H0V8h4V5.5C4 1.789 6.298 0 9.61 0c1.585 0 2.948.118 3.345.17v3.88H10.66c-1.8 0-2.15.856-2.15 2.112V8h5.241l-2 4H8.51v10H4.032z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"whatsapp\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Whatsapp\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg xmlns='http: \/\/www.w3.org\/2000\/svg' width='25' height='24' viewBox='0 0 25 24'><path d='M.805 24l1.687-6.163a11.869 11.869 0 01-1.588-5.945C.907 5.335 6.244 0 12.801 0c3.182.001 6.17 1.24 8.415 3.488a11.819 11.819 0 013.481 8.413c-.002 6.558-5.34 11.893-11.896 11.893h-.005c-1.99-.001-3.947-.5-5.685-1.448L.805 24zm6.598-3.807l.361.214a9.874 9.874 0 005.033 1.378h.004c5.45 0 9.885-4.434 9.888-9.885a9.824 9.824 0 00-2.894-6.993 9.823 9.823 0 00-6.99-2.898c-5.454 0-9.89 4.434-9.892 9.884a9.86 9.86 0 001.512 5.26l.235.374-.999 3.648 3.742-.982z' fill='currentColor'\/><path d='M9.825 6.921c-.24-.58-.486-.501-.668-.51-.174-.009-.372-.01-.57-.01-.198 0-.52.074-.793.371-.272.298-1.04 1.017-1.04 2.48 0 1.462 1.065 2.875 1.214 3.073.148.199 2.096 3.2 5.078 4.487.709.306 1.262.49 1.694.626.712.226 1.36.194 1.872.118.571-.085 1.759-.72 2.007-1.413.247-.694.247-1.29.173-1.413-.074-.124-.272-.199-.57-.347-.297-.149-1.758-.868-2.03-.967-.273-.1-.471-.149-.67.149-.198.297-.767.966-.94 1.165-.174.198-.348.223-.645.074-.297-.149-1.255-.462-2.39-1.475-.884-.788-1.48-1.76-1.654-2.058-.173-.298-.018-.459.13-.607.134-.133.298-.347.446-.52.149-.174.199-.298.298-.496.099-.198.05-.372-.025-.52-.074-.15-.669-1.612-.917-2.207z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F&#038;text=Eine%20virtuelle%20Zeitreise%20durch%20die%20Musikgeschichte\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"twitter\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Twitter\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg width='25' height='20' viewBox='0 0 25 20' fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg'><path d='M24.75 2.3c-.9.4-1.8.7-2.8.8 1-.6 1.8-1.6 2.2-2.7-1 .6-2 1-3.1 1.2-.9-1-2.2-1.6-3.6-1.6-2.7 0-4.9 2.2-4.9 4.9 0 .4 0 .8.1 1.1-4.2-.2-7.8-2.2-10.2-5.2-.5.8-.7 1.6-.7 2.5 0 1.7.9 3.2 2.2 4.1-.8 0-1.6-.2-2.2-.6v.1c0 2.4 1.7 4.4 3.9 4.8-.4.1-.8.2-1.3.2-.3 0-.6 0-.9-.1.6 2 2.4 3.4 4.6 3.4-1.7 1.3-3.8 2.1-6.1 2.1-.4 0-.8 0-1.2-.1 2.2 1.4 4.8 2.2 7.5 2.2 9.1 0 14-7.5 14-14v-.6c1-.7 1.8-1.6 2.5-2.5z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"linkedin\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Linkedin\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg width='19' height='18' viewBox='0 0 19 18' fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg'><path d='M1.15 17.3h3.6V5.8h-3.6v11.5zM.75 2.1c0 1.2 1 2.1 2.1 2.1 1.2 0 2.1-.9 2.1-2.1 0-1.2-1-2.1-2.1-2.1-1.2 0-2.1 1-2.1 2.1zM14.45 17.3h3.6v-6.2c0-3.1-.7-5.5-4.3-5.5-1.8 0-2.9.9-3.4 1.8V5.8h-3.4v11.5h3.6v-5.7c0-1.5.2-2.9 2.1-2.9 1.8 0 1.8 1.7 1.8 3v5.6z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t<\/div>\n<\/div>\n\n<div class=\"block-title-and-content js-block-title-and-content block-title-and-content__theme--onyxGrey\">\n\t<div class=\"block-title-and-content__layout\">\n\t\t<h2\t\tclass=\"typography block-title-and-content__title typography__color--white typography__size--h2 typography__align--left\"\n\t\tdata-size-mobile=\"h2\" \t>\n\t\tFakten und Visualisierungen\t<\/h2>\n\t\t\t\t\t<div class=\"block-title-and-content__content\">\n\t\t\t\t\n<div class='block-title-and-content__item'><div class='block-title-and-content__item-inner'><p\t\tclass=\"typography block-typography__typography typography__color--lightGrey typography__size--regular-body typography__align--left\"\n\t\t\t>\n\t\tDer Datensatz der Schweizer Hitparade ist eine der weltweit umfangreichsten Sammlungen zur Mainstream-Musik. Das interaktive Erlebnis spielt nur mit einem kleinen Teil davon. Weitere interessante Daten werden auf mehreren zus\u00e4tzlichen Plattformen visualisiert &#8211; von W\u00f6rtern in Songtitel, akustischen Tonarten und Coverversionen bis hin zu Schweizer Songs und K\u00fcnstler:innen in den ersten 50 Jahren der CH-Hitparade.\t<\/p><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\t<div class=\"block-title-and-content__social-links\">\n\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"copy\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Copy page link\"\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tdata-tooltip=\"true\"\n\t\t\t\t\tdata-tooltip-text=\"Link copied to clipboard.\"\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg' width='22' height='22' viewBox='0 0 22 22'><path d='M6.832 15.167l8.333-8.333M9.332 6.001l2.787-2.787a4.715 4.715 0 016.666 0v0a4.715 4.715 0 010 6.667L16 12.668M5.999 9.334l-2.787 2.787a4.715 4.715 0 000 6.666v0a4.715 4.715 0 006.667 0l2.787-2.786' stroke='currentColor' stroke-width='2'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"facebook\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Facebook\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg width='14' height='22' viewBox='0 0 14 22' fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg'><path d='M4.032 22L4 12H0V8h4V5.5C4 1.789 6.298 0 9.61 0c1.585 0 2.948.118 3.345.17v3.88H10.66c-1.8 0-2.15.856-2.15 2.112V8h5.241l-2 4H8.51v10H4.032z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"whatsapp\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Whatsapp\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg xmlns='http: \/\/www.w3.org\/2000\/svg' width='25' height='24' viewBox='0 0 25 24'><path d='M.805 24l1.687-6.163a11.869 11.869 0 01-1.588-5.945C.907 5.335 6.244 0 12.801 0c3.182.001 6.17 1.24 8.415 3.488a11.819 11.819 0 013.481 8.413c-.002 6.558-5.34 11.893-11.896 11.893h-.005c-1.99-.001-3.947-.5-5.685-1.448L.805 24zm6.598-3.807l.361.214a9.874 9.874 0 005.033 1.378h.004c5.45 0 9.885-4.434 9.888-9.885a9.824 9.824 0 00-2.894-6.993 9.823 9.823 0 00-6.99-2.898c-5.454 0-9.89 4.434-9.892 9.884a9.86 9.86 0 001.512 5.26l.235.374-.999 3.648 3.742-.982z' fill='currentColor'\/><path d='M9.825 6.921c-.24-.58-.486-.501-.668-.51-.174-.009-.372-.01-.57-.01-.198 0-.52.074-.793.371-.272.298-1.04 1.017-1.04 2.48 0 1.462 1.065 2.875 1.214 3.073.148.199 2.096 3.2 5.078 4.487.709.306 1.262.49 1.694.626.712.226 1.36.194 1.872.118.571-.085 1.759-.72 2.007-1.413.247-.694.247-1.29.173-1.413-.074-.124-.272-.199-.57-.347-.297-.149-1.758-.868-2.03-.967-.273-.1-.471-.149-.67.149-.198.297-.767.966-.94 1.165-.174.198-.348.223-.645.074-.297-.149-1.255-.462-2.39-1.475-.884-.788-1.48-1.76-1.654-2.058-.173-.298-.018-.459.13-.607.134-.133.298-.347.446-.52.149-.174.199-.298.298-.496.099-.198.05-.372-.025-.52-.074-.15-.669-1.612-.917-2.207z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F&#038;text=Eine%20virtuelle%20Zeitreise%20durch%20die%20Musikgeschichte\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"twitter\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Twitter\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg width='25' height='20' viewBox='0 0 25 20' fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg'><path d='M24.75 2.3c-.9.4-1.8.7-2.8.8 1-.6 1.8-1.6 2.2-2.7-1 .6-2 1-3.1 1.2-.9-1-2.2-1.6-3.6-1.6-2.7 0-4.9 2.2-4.9 4.9 0 .4 0 .8.1 1.1-4.2-.2-7.8-2.2-10.2-5.2-.5.8-.7 1.6-.7 2.5 0 1.7.9 3.2 2.2 4.1-.8 0-1.6-.2-2.2-.6v.1c0 2.4 1.7 4.4 3.9 4.8-.4.1-.8.2-1.3.2-.3 0-.6 0-.9-.1.6 2 2.4 3.4 4.6 3.4-1.7 1.3-3.8 2.1-6.1 2.1-.4 0-.8 0-1.2-.1 2.2 1.4 4.8 2.2 7.5 2.2 9.1 0 14-7.5 14-14v-.6c1-.7 1.8-1.6 2.5-2.5z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t\t\t<a\n\t\t\t\thref=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fwww.deptagency.com%2Fde-dach%2Fcase%2Feine-virtuelle-zeitreise-durch-die-musikgeschichte%2F\"\n\t\t\t\tdata-share-url=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\"\n\t\t\t\tdata-share-title=\"Eine virtuelle Zeitreise durch die Musikgeschichte\"\n\t\t\t\tdata-share-type=\"linkedin\"\n\t\t\t\tclass=\"block-title-and-content__social-links-item js-social-link\"\n\t\t\t\taria-label=\"Share to Linkedin\"\n\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\trel=\"noopener noreferrer\"\n\t\t\t\t\n\t\t\t\t\t\t\t>\n\t\t\t\t<svg width='19' height='18' viewBox='0 0 19 18' fill='none' xmlns='http: \/\/www.w3.org\/2000\/svg'><path d='M1.15 17.3h3.6V5.8h-3.6v11.5zM.75 2.1c0 1.2 1 2.1 2.1 2.1 1.2 0 2.1-.9 2.1-2.1 0-1.2-1-2.1-2.1-2.1-1.2 0-2.1 1-2.1 2.1zM14.45 17.3h3.6v-6.2c0-3.1-.7-5.5-4.3-5.5-1.8 0-2.9.9-3.4 1.8V5.8h-3.4v11.5h3.6v-5.7c0-1.5.2-2.9 2.1-2.9 1.8 0 1.8 1.7 1.8 3v5.6z' fill='currentColor'\/><\/svg>\t\t\t<\/a>\n\t\t\t\t<\/div>\n<\/div>\n\n<div class=\"call-to-action block-call-to-action__call-to-action call-to-action__background-color--white\">\n\n\t<p class=\"paragraph paragraph__color--richBlack paragraph__align--center call-to-action__paragraph\">Erleben Sie <a href=\"https:\/\/50-jahre-hitparade.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">50 Jahre Hitparade<\/a><\/p>\n<\/div>\n\n<div class=\"block-get-in-touch js-block-get-in-touch\">\n\t<div class=\"block-get-in-touch__column block-get-in-touch__column--left block-get-in-touch__column--richBlack\">\n\t\t<h2 class=\"heading heading__color--white heading__size--xl heading__align--left block-get-in-touch__heading\">\n\t\t\tFragen?\t<\/h2>\t<\/div>\n\n\t<div class=\"block-get-in-touch__column block-get-in-touch__column--right block-get-in-touch__column--white\">\n\t<div\n\t\tclass=\"image-wrap block-get-in-touch__image-wrap\"\n\t\tdata-align=\"top center\"\n\t\t\t>\n\n\t\t\t<div style=\"background-image:url(https:\/\/www.deptagency.com\/wp-content\/uploads\/2023\/11\/yann-wanner-1.jpg)\" class=\"image image--bg block-get-in-touch__image\" ><\/div>\n\t\n\t<\/div>\t\t\t<div class=\"block-get-in-touch__specialist\">\n\t\t\t\t<p class=\"heading heading__color--richBlack heading__size--xxs heading__align--left block-get-in-touch__subtitle\">\n\t\t\tDirector Business Development\t<\/p><h3 class=\"heading heading__color--richBlack heading__size--m heading__align--left block-get-in-touch__person-title\">\n\t\t\tYann Wanner\t<\/h3>\t\t\t<\/div>\n\t\t\n\t\t<button\tclass=\"cta-bar block-get-in-touch__cta-bar js-cta-bar\"\n\tid=\"block-get-in-touch-9b2ecdde555970d649511ae7284a4e9c\"\n\ttitle=\"Get in touch\"\n\taria-label=\"\"\n\t\t>\n\t<div class=\"cta-bar__container cta-bar__container--size--default\">\n\t\t<div class=\"cta-bar__content\">\n\t\t\t<span class=\"cta-bar__label\">\n\t\t\t\tGet in touch\t\t\t<\/span>\n\t\t\t<i class=\"icon icon icon__color--white icon__size--small icon__arrow-right-circle cta-bar__icon cta-bar__icon\">\n\t<svg width='24' height='24' fill='none' viewBox='0 0 24 24' xmlns='http:\/\/www.w3.org\/2000\/svg'><g class='symbol'><path d='M11.5215 17.2609L17.2607 12L11.5215 6.73912' stroke='currentColor' stroke-width='1.5' stroke-miterlimit='10'\/><path d='M16.7827 12L6.26099 12' stroke='currentColor' stroke-width='1.5' stroke-miterlimit='10'\/><circle cx='12' cy='12' r='11' stroke='currentColor' stroke-width='1.5' stroke-miterlimit='10'\/><\/g><path class='symbol-hover' fill-rule='evenodd' clip-rule='evenodd' d='M23 12C23 5.92487 18.0751 0.999999 12 1C5.92487 1 1 5.92487 1 12C1 18.0751 5.92487 23 12 23C18.0751 23 23 18.0751 23 12ZM17.7674 11.4471L12.0283 6.18627L11.0147 7.292L15.3326 11.25L6.26099 11.25L6.26099 12.75L15.3326 12.75L11.0147 16.708L12.0283 17.8137L17.7675 12.5529L18.3706 12L17.7674 11.4471Z' fill='currentColor'\/><\/svg><\/i>\t\t<\/div>\n\t<\/div>\n<\/button>\t<\/div>\n<\/div>\n\n<div\n\tclass=\"flyout-drawer js-flyout-drawer flyout-drawer__position--right\"\n\tdata-trigger=\"#block-get-in-touch-9b2ecdde555970d649511ae7284a4e9c\"\n\tdata-instant-open=\"false\"\n>\n\t<div class=\"flyout-drawer__left-mobile-backplate\"><\/div>\n\t<div class=\"flyout-drawer__left-backplate\"><\/div>\n\n\t\t<div class=\"flyout-drawer__left\"><\/div>\n\n\t<button\tclass=\"cta-button flyout-drawer__close cta-button__color--white cta-button__style--text-and-icon js-drawer-close has-flipped-icon\" aria-label=\"Close\" >\n\t<svg width='21' height='21' viewBox='0 0 21 21' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'><circle cx='10.5' cy='10.5' r='9.5' transform='rotate(-90 10.5 10.5)' stroke='var(--dept-button-icon-outline-color)' stroke-width='1.3' stroke-miterlimit='10' fill='none'\/><circle class='icon-backplate' cx='10.5' cy='10.5' r='9.5' transform='rotate(-90 10.5 10.5)' fill='var(--dept-button-icon-backplate-color)' fill-opacity='1'\/><path class='icon-center' d='m14 7-7 7m0-7 7 7' stroke='var(--dept-button-icon-color)' stroke-width='1.5' fill='none'\/><\/svg>\n\t\t\t<span>\n\t\t\tClose\t\t<\/span>\n\t\n<\/button>\n\t<div class=\"flyout-drawer__right\">\n\t\t<div class=\"pardot-forms block-get-in-touch__pardot-forms js-pardot-forms\">\n\t\t<iframe\n\t\tdata-initial-src=\"https:\/\/www2.deptagency.com\/l\/321011\/2018-08-06\/gzmj3x\"\n\t\tclass=\"pardot-forms__embed block-get-in-touch__embed js-pardot-forms-embed\"\n\t\ttype=\"text\/html\"\n\t><\/iframe>\n\t<div class=\"loader pardot-forms__loader loader__color--hanPurple js-pardot-forms-loader\">\n\t<div class=\"loader__first\"><\/div>\n\t<div class=\"loader__second\"><\/div>\n<\/div><\/div>\t<\/div>\n\n\t<button\tclass=\"cta-button flyout-drawer__back cta-button__color--onyxGrey cta-button__style--text-and-icon js-drawer-back has-small-icon\" aria-label=\"Back\" >\n\t<svg width='41' height='41' viewBox='0 0 41 41' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'><circle cx='20.5' cy='20.5' r='19.5' transform='rotate(-90 20.5 20.5)' stroke='var(--dept-button-icon-outline-color)' stroke-width='1.3' stroke-miterlimit='10' fill='none'\/><circle class='icon-backplate' cx='20.5' cy='20.5' r='19.5' transform='rotate(-90 20.5 20.5)' fill='var(--dept-button-icon-backplate-color)' fill-opacity='1'\/><path class='icon-center' d='M21.174 30 11 20.674l10.174-9.326m-9.326 9.328H30.5' stroke='var(--dept-button-icon-color)' stroke-width='1.3' stroke-miterlimit='10' fill='none'\/><\/svg>\n\t\t\t<span>\n\t\t\tBack\t\t<\/span>\n\t\n<\/button><\/div>\n\n<div class=\"block-highlighted-cases\" data-theme=\"white\">\n\t<p\t\tclass=\"typography block-highlighted-cases__heading typography__color--onyxGrey typography__size--regular-body typography__align--left\"\n\t\t\t>\n\t\tMehr erfahren\t<\/p>\n\t<div class=\"block-highlighted-cases__projects\">\n\t\t<a\tclass=\"universal-item-card universal-item-card__type--case universal-item-card--has-link-decoration block-highlighted-cases__project is-title-and-meta-swapped\"\n\tdata-theme=\"white\"\n\t\t\thref=\"https:\/\/www.deptagency.com\/de-dach\/case\/die-zukunft-der-mode-veraendern-rotates-digitale-evolution\/\"\n\t\t\t\ttitle=\"Birger Christensen Collective\"\n\t\t>\n\t\n\t<div\n\t\tclass=\"image-wrap universal-item-card__image-wrap\"\n\t\tdata-align=\"center center\"\n\t\t\t>\n\n\t\t\t<picture\n\t\tclass=\"image__picture\"\n\t\t\t\t>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<img\n\t\t\t\tsrc=\"https:\/\/www.deptagency.com\/wp-content\/uploads\/2023\/12\/Rotate-featured.jpg\"\n\t\t\t\tclass=\"image universal-item-card__image\"\n\n\t\t\t\t\t\t\t\talt=\"Birger Christensen Collective\"\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\/>\n\t\t<\/picture>\n\t\n\t<\/div><p\t\tclass=\"typography universal-item-card__meta typography__color--darkGrey typography__size--eyebrow-lc typography__align--left\"\n\t\t\t>\n\t\tRevitalizing ROTATE: Ein mutiges E-Commerce Replatforming\t<\/p><h3\t\tclass=\"typography universal-item-card__title typography__color--onyxGrey typography__size--h6 typography__align--left\"\n\t\t\t>\n\t\t<span>Birger Christensen Collective<\/span>\t<\/h3>\n\t\n\t<\/a><a\tclass=\"universal-item-card universal-item-card__type--case universal-item-card--has-link-decoration block-highlighted-cases__project is-title-and-meta-swapped\"\n\tdata-theme=\"white\"\n\t\t\thref=\"https:\/\/www.deptagency.com\/de-dach\/case\/transavia\/\"\n\t\t\t\ttitle=\"Transavia\"\n\t\t>\n\t\n\t<div\n\t\tclass=\"image-wrap universal-item-card__image-wrap\"\n\t\tdata-align=\"center center\"\n\t\t\t>\n\n\t\t\t<picture\n\t\tclass=\"image__picture\"\n\t\t\t\t>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<img\n\t\t\t\tsrc=\"https:\/\/www.deptagency.com\/wp-content\/uploads\/2021\/07\/iStock-1188236181-1-scaled.jpg\"\n\t\t\t\tclass=\"image universal-item-card__image\"\n\n\t\t\t\t\t\t\t\talt=\"Transavia\"\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\/>\n\t\t<\/picture>\n\t\n\t<\/div><p\t\tclass=\"typography universal-item-card__meta typography__color--darkGrey typography__size--eyebrow-lc typography__align--left\"\n\t\t\t>\n\t\tIn neuen Dimensionen abheben\t<\/p><h3\t\tclass=\"typography universal-item-card__title typography__color--onyxGrey typography__size--h6 typography__align--left\"\n\t\t\t>\n\t\t<span>Transavia<\/span>\t<\/h3>\n\t\n\t<\/a>\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Was w\u00e4re, wenn man in die Vergangenheit reisen k\u00f6nnte, um zu h\u00f6ren, wie die Schweizer Hitparade in den letzten 50 Jahren geklungen hat?","protected":false},"author":1,"featured_media":4255834,"template":"","meta":{"_acf_changed":false,"es_utils_meta_schema":"","dept_alt_featured_image":[],"dept_algolia_noindex":false,"dept_algolia_featured":false,"member_job_title":"","member_linkedin_url":"","dept_accent_color":"#1027EF","dept_next_case_accent_color":"","dept_case_video":{"type":"local"},"footnotes":""},"client":[1536],"person":[1533],"award":[1537,1010,1531,1539,1541,1538,1540],"case-category":[42483],"case-industry":[42492],"class_list":["post-4255833","case","type-case","status-publish","has-post-thumbnail","hentry"],"acf":{"dept_is_3q_page":false,"dept_current_cpt_partner":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eine virtuelle Zeitreise durch die Musikgeschichte - DEPT\u00ae<\/title>\n<meta name=\"description\" content=\"Was w\u00e4re, wenn man in die Vergangenheit reisen k\u00f6nnte, um zu h\u00f6ren, wie die Schweizer Hitparade in den letzten 50 Jahren geklungen hat?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eine virtuelle Zeitreise durch die Musikgeschichte - DEPT\u00ae\" \/>\n<meta property=\"og:description\" content=\"Was w\u00e4re, wenn man in die Vergangenheit reisen k\u00f6nnte, um zu h\u00f6ren, wie die Schweizer Hitparade in den letzten 50 Jahren geklungen hat?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/\" \/>\n<meta property=\"og:site_name\" content=\"DEPT\u00ae\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deptagency.com\/wp-content\/uploads\/2021\/12\/50-years-swiss-music-charts.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2100\" \/>\n\t<meta property=\"og:image:height\" content=\"1493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deptagency.com\\\/de-dach\\\/case\\\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\\\/\",\"url\":\"https:\\\/\\\/www.deptagency.com\\\/de-dach\\\/case\\\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\\\/\",\"name\":\"Eine virtuelle Zeitreise durch die Musikgeschichte - DEPT\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deptagency.com\\\/en-uki\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deptagency.com\\\/de-dach\\\/case\\\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deptagency.com\\\/de-dach\\\/case\\\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deptagency.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/50-years-swiss-music-charts.jpg\",\"datePublished\":\"2021-12-08T16:41:23+00:00\",\"description\":\"Was w\u00e4re, wenn man in die Vergangenheit reisen k\u00f6nnte, um zu h\u00f6ren, wie die Schweizer Hitparade in den letzten 50 Jahren geklungen hat?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deptagency.com\\\/de-dach\\\/case\\\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\\\/#breadcrumb\"},\"inLanguage\":\"global-GLOBAL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deptagency.com\\\/de-dach\\\/case\\\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"global-GLOBAL\",\"@id\":\"https:\\\/\\\/www.deptagency.com\\\/de-dach\\\/case\\\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deptagency.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/50-years-swiss-music-charts.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deptagency.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/50-years-swiss-music-charts.jpg\",\"width\":2100,\"height\":1493},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deptagency.com\\\/de-dach\\\/case\\\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.deptagency.com\\\/de-dach\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eine virtuelle Zeitreise durch die Musikgeschichte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deptagency.com\\\/en-uki\\\/#website\",\"url\":\"https:\\\/\\\/www.deptagency.com\\\/en-uki\\\/\",\"name\":\"DEPT\u00ae\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deptagency.com\\\/en-uki\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"global-GLOBAL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eine virtuelle Zeitreise durch die Musikgeschichte - DEPT\u00ae","description":"Was w\u00e4re, wenn man in die Vergangenheit reisen k\u00f6nnte, um zu h\u00f6ren, wie die Schweizer Hitparade in den letzten 50 Jahren geklungen hat?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/","og_locale":"en_US","og_type":"article","og_title":"Eine virtuelle Zeitreise durch die Musikgeschichte - DEPT\u00ae","og_description":"Was w\u00e4re, wenn man in die Vergangenheit reisen k\u00f6nnte, um zu h\u00f6ren, wie die Schweizer Hitparade in den letzten 50 Jahren geklungen hat?","og_url":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/","og_site_name":"DEPT\u00ae","og_image":[{"width":2100,"height":1493,"url":"https:\/\/www.deptagency.com\/wp-content\/uploads\/2021\/12\/50-years-swiss-music-charts.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/","url":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/","name":"Eine virtuelle Zeitreise durch die Musikgeschichte - DEPT\u00ae","isPartOf":{"@id":"https:\/\/www.deptagency.com\/en-uki\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/#primaryimage"},"image":{"@id":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deptagency.com\/wp-content\/uploads\/2021\/12\/50-years-swiss-music-charts.jpg","datePublished":"2021-12-08T16:41:23+00:00","description":"Was w\u00e4re, wenn man in die Vergangenheit reisen k\u00f6nnte, um zu h\u00f6ren, wie die Schweizer Hitparade in den letzten 50 Jahren geklungen hat?","breadcrumb":{"@id":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/#breadcrumb"},"inLanguage":"global-GLOBAL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/"]}]},{"@type":"ImageObject","inLanguage":"global-GLOBAL","@id":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/#primaryimage","url":"https:\/\/www.deptagency.com\/wp-content\/uploads\/2021\/12\/50-years-swiss-music-charts.jpg","contentUrl":"https:\/\/www.deptagency.com\/wp-content\/uploads\/2021\/12\/50-years-swiss-music-charts.jpg","width":2100,"height":1493},{"@type":"BreadcrumbList","@id":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.deptagency.com\/de-dach\/"},{"@type":"ListItem","position":2,"name":"Eine virtuelle Zeitreise durch die Musikgeschichte"}]},{"@type":"WebSite","@id":"https:\/\/www.deptagency.com\/en-uki\/#website","url":"https:\/\/www.deptagency.com\/en-uki\/","name":"DEPT\u00ae","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deptagency.com\/en-uki\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"global-GLOBAL"}]}},"listingData":{"imageUrl":"https:\/\/www.deptagency.com\/wp-content\/uploads\/2021\/12\/50-years-swiss-music-charts.jpg","imageAlt":"","caseVideo":{"type":"local"},"url":"https:\/\/www.deptagency.com\/de-dach\/case\/eine-virtuelle-zeitreise-durch-die-musikgeschichte\/","hoverColor":"#1027EF","hoverText":"Eine virtuelle Zeitreise durch die Musikgeschichte","label":"Hitparade.ch","tags":["Customer Experience","Kunst &amp; Kultur"]},"_links":{"self":[{"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/case\/4255833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/case"}],"about":[{"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/types\/case"}],"author":[{"embeddable":true,"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/case\/4255833\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/media\/4255834"}],"wp:attachment":[{"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/media?parent=4255833"}],"wp:term":[{"taxonomy":"client","embeddable":true,"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/client?post=4255833"},{"taxonomy":"person","embeddable":true,"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/person?post=4255833"},{"taxonomy":"award","embeddable":true,"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/award?post=4255833"},{"taxonomy":"case-category","embeddable":true,"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/case-category?post=4255833"},{"taxonomy":"case-industry","embeddable":true,"href":"https:\/\/www.deptagency.com\/de-dach\/wp-json\/wp\/v2\/case-industry?post=4255833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}